{"id":122,"count":1,"description":"\u5373\u5c07\u8209\u884c\u7684\u6d3b\u52d5","link":"https:\/\/www.wholesome.global\/zh-hant\/category\/%e5%8d%b3%e5%b0%87%e8%88%89%e8%a1%8c%e7%9a%84%e6%b4%bb%e5%8b%95\/","name":"\u5373\u5c07\u8209\u884c\u7684\u6d3b\u52d5","slug":"%e5%8d%b3%e5%b0%87%e8%88%89%e8%a1%8c%e7%9a%84%e6%b4%bb%e5%8b%95","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.wholesome.global\/zh-hant\/wp-json\/wp\/v2\/categories\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wholesome.global\/zh-hant\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.wholesome.global\/zh-hant\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.wholesome.global\/zh-hant\/wp-json\/wp\/v2\/posts?categories=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}